{"id":11500,"date":"2025-09-08T14:18:43","date_gmt":"2025-09-08T17:18:43","guid":{"rendered":"https:\/\/fecomercio-pe.com.br\/site\/?p=11500"},"modified":"2025-09-08T14:25:38","modified_gmt":"2025-09-08T17:25:38","slug":"missao-empresarial-da-fecomercio-pe-inicia-programacao-em-toquio-com-foco-em-inovacao-e-cooperacao","status":"publish","type":"post","link":"https:\/\/fecomercio-pe.com.br\/site\/missao-empresarial-da-fecomercio-pe-inicia-programacao-em-toquio-com-foco-em-inovacao-e-cooperacao\/","title":{"rendered":"Miss\u00e3o Empresarial da Fecom\u00e9rcio-PE inicia programa\u00e7\u00e3o em T\u00f3quio com foco em inova\u00e7\u00e3o e coopera\u00e7\u00e3o"},"content":{"rendered":"<p><em><span style=\"font-weight: 400;\">Comitiva pernambucana cumpre agenda no Jap\u00e3o em busca de ampliar oportunidades em setores estrat\u00e9gicos<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400;\">A 20\u00aa Miss\u00e3o Empresarial organizada pela Federa\u00e7\u00e3o do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo do Estado de Pernambuco (Fecom\u00e9rcio-PE), que acontece com apoio da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo (CNC) Sesc PE, Senac PE e do Sebrae\/PE, iniciou sua programa\u00e7\u00e3o em T\u00f3quio, capital do Jap\u00e3o. A comitiva re\u00fane 65 integrantes, entre empres\u00e1rios, representantes de entidades de classe, autoridades p\u00fablicas e dirigentes de institui\u00e7\u00f5es de outros estados, como Rio de Janeiro e Rio Grande do Norte, e cumpre uma agenda voltada para a inova\u00e7\u00e3o, a coopera\u00e7\u00e3o internacional e o fortalecimento das rela\u00e7\u00f5es comerciais com o Jap\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A programa\u00e7\u00e3o incluiu visitas t\u00e9cnicas a institui\u00e7\u00f5es de refer\u00eancia, encontros com lideran\u00e7as empresariais japonesas e participa\u00e7\u00e3o em reuni\u00f5es estrat\u00e9gicas. O objetivo \u00e9 identificar oportunidades de investimento, promover a troca de experi\u00eancias e estimular pr\u00e1ticas que possam ser aplicadas no Brasil, especialmente em \u00e1reas como tecnologia, educa\u00e7\u00e3o, qualifica\u00e7\u00e3o profissional, turismo e servi\u00e7os. A experi\u00eancia japonesa no cuidado com a popula\u00e7\u00e3o idosa tamb\u00e9m foi apontada como um modelo a ser estudado pela delega\u00e7\u00e3o brasileira.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pela manh\u00e3, a comitiva foi recebida na Ag\u00eancia de Coopera\u00e7\u00e3o Internacional do Jap\u00e3o (JICA) pelo diretor da Divis\u00e3o Am\u00e9rica do Sul, Aoki Issei, pela integrante da mesma divis\u00e3o, Hatanaka Haruka, e pelo diretor-geral do Departamento para Am\u00e9rica Latina e Caribe, Ito Keisuke. O encontro rendeu resultados imediatos, com reuni\u00f5es j\u00e1 agendadas para o retorno da miss\u00e3o aos escrit\u00f3rios da ag\u00eancia em S\u00e3o Paulo e Bras\u00edlia. A expectativa \u00e9 apresentar projetos de entidades privadas e do setor p\u00fablico, com foco na capta\u00e7\u00e3o de recursos para Pernambuco e para o Nordeste.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0 tarde, a delega\u00e7\u00e3o esteve na Organiza\u00e7\u00e3o de Com\u00e9rcio Exterior do Jap\u00e3o (JETRO), ag\u00eancia p\u00fablica japonesa dedicada ao fomento \u00e0 inova\u00e7\u00e3o e \u00e0s estrat\u00e9gias globais. Participaram Takao Nakahata, diretor s\u00eanior para estrat\u00e9gias globais com foco na Am\u00e9rica Latina, al\u00e9m de Kenyu Konishi e Yuki Furuki, executivos respons\u00e1veis pelo mesmo eixo. O di\u00e1logo tratou de oportunidades de interc\u00e2mbio em tecnologia, inova\u00e7\u00e3o e com\u00e9rcio exterior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na sequ\u00eancia, o Banco do Brasil apresentou sua atua\u00e7\u00e3o na \u00c1sia. O gerente-geral da unidade em T\u00f3quio, Alisson Aguiar da Costa, e a gerente-geral adjunta, Bruna Cortella, destacaram a relev\u00e2ncia do continente asi\u00e1tico, que concentra 61% da popula\u00e7\u00e3o mundial, com 5 bilh\u00f5es de pessoas, al\u00e9m de responder por 35% do PIB global. Segundo o banco, o papel da institui\u00e7\u00e3o \u00e9 atuar como ponte entre empresas brasileiras e o mercado asi\u00e1tico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No segundo dia de programa\u00e7\u00e3o em T\u00f3quio, a comitiva realizou uma visita protocolar \u00e0 Embaixada do Brasil no Jap\u00e3o, onde o grupo foi recebido pelo ministro Ronaldo Amaral, chefe do setor comercial. Na C\u00e2mara de Com\u00e9rcio Brasileira no Jap\u00e3o (CCBJ), a delega\u00e7\u00e3o foi recepcionada pelo presidente Celso Guiotoko, pelo vice-presidente Alisson Aguiar e pelo diretor Hiroyuki Shimizu, em encontro que refor\u00e7ou a integra\u00e7\u00e3o empresarial entre os dois pa\u00edses.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Segundo Antonio Florencio, presidente do Sistema Fecom\u00e9rcio\/Sesc\/Senac RJ, a miss\u00e3o representa uma oportunidade \u00fanica de aprendizado e integra\u00e7\u00e3o entre os dois pa\u00edses. \u201cO Jap\u00e3o \u00e9 um exemplo de sociedade que respeita valores coletivos e que investe de forma consistente em educa\u00e7\u00e3o e no aproveitamento da experi\u00eancia dos seus idosos. Essa combina\u00e7\u00e3o gera estabilidade social e econ\u00f4mica. No Brasil, ainda temos um longo caminho a percorrer, mas h\u00e1 muito a aprender com a disciplina e o senso comunit\u00e1rio que encontramos aqui. O trabalho integrado entre as federa\u00e7\u00f5es do Rio de Janeiro e de Pernambuco \u00e9 fundamental para traduzir essas observa\u00e7\u00f5es em pr\u00e1ticas aplic\u00e1veis ao nosso pa\u00eds\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gabriel Chalita, consultor do Sesc e Senac RJ, ressaltou a import\u00e2ncia do interc\u00e2mbio como inspira\u00e7\u00e3o para novas pol\u00edticas no Brasil. \u201cChegar ao Jap\u00e3o e ver de perto como a educa\u00e7\u00e3o \u00e9 estruturada, com forte car\u00e1ter coletivo e voltado ao bem comum, \u00e9 algo que nos faz repensar pr\u00e1ticas no Brasil. Nosso pa\u00eds tem grande potencial criativo e cultural, mas ainda carrega marcas de um individualismo que precisa ser superado. O aprendizado com experi\u00eancias internacionais, como esta, \u00e9 essencial para que possamos formar cidad\u00e3os mais conscientes e criar pol\u00edticas p\u00fablicas mais s\u00f3lidas na educa\u00e7\u00e3o e na inclus\u00e3o social\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para o presidente do Sistema Fecom\u00e9rcio\/Sesc\/Senac-PE, Bernardo Peixoto, o Jap\u00e3o continua como um dos maiores investidores globais em tecnologia, inova\u00e7\u00e3o e infraestrutura, e para Pernambuco esta miss\u00e3o representa uma oportunidade \u00edmpar de ampliar nossas exporta\u00e7\u00f5es, firmar parcerias comerciais e atrair pr\u00e1ticas bem-sucedidas que possam fortalecer o setor de servi\u00e7os, o com\u00e9rcio e o turismo. Segundo ele, \u00e9 fundamental que o empresariado pernambucano esteja inserido em uma agenda global capaz de diversificar mercados, aumentar a competitividade e trazer experi\u00eancias valiosas de inova\u00e7\u00e3o, gest\u00e3o e tecnologia aplic\u00e1veis no nosso dia a dia. \u201c\u00c9 uma oportunidade de aprendizado, de troca de conhecimento e de estreitamento de la\u00e7os que v\u00e3o beneficiar n\u00e3o apenas os neg\u00f3cios, mas todo o desenvolvimento econ\u00f4mico e social de Pernambuco&#8221;, afirma o presidente.\u00a0<\/span><\/p>\n<p><b>MISS\u00c3O &#8211;<\/b><span style=\"font-weight: 400;\"> Nos pr\u00f3ximos dias, a programa\u00e7\u00e3o da miss\u00e3o seguir\u00e1 com a viagem da comitiva para Shenzhen, na China, onde est\u00e3o previstas visitas t\u00e9cnicas a empresas e centros de inova\u00e7\u00e3o, incluindo a sede da Huawei e o Shenzhen Open Innovation Lab. O roteiro ser\u00e1 conclu\u00eddo em Pequim, com a participa\u00e7\u00e3o na China International Fair for Trade in Services (CIFTIS) e em um semin\u00e1rio sobre oportunidades de investimentos e neg\u00f3cios no Nordeste do Brasil.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comitiva pernambucana cumpre agenda no Jap\u00e3o em busca de ampliar oportunidades em setores estrat\u00e9gicos A 20\u00aa Miss\u00e3o Empresarial organizada pela Federa\u00e7\u00e3o do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo do Estado de Pernambuco (Fecom\u00e9rcio-PE), que acontece com apoio da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo (CNC) Sesc PE, Senac PE e do Sebrae\/PE,<br \/><a href=\"https:\/\/fecomercio-pe.com.br\/site\/missao-empresarial-da-fecomercio-pe-inicia-programacao-em-toquio-com-foco-em-inovacao-e-cooperacao\/\" class=\"more\">Read more<\/a><\/p>\n","protected":false},"author":12,"featured_media":11501,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4],"tags":[],"_links":{"self":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/11500"}],"collection":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/comments?post=11500"}],"version-history":[{"count":1,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/11500\/revisions"}],"predecessor-version":[{"id":11502,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/11500\/revisions\/11502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/media\/11501"}],"wp:attachment":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/media?parent=11500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/categories?post=11500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/tags?post=11500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}