{"id":10610,"date":"2024-09-10T08:18:30","date_gmt":"2024-09-10T11:18:30","guid":{"rendered":"https:\/\/fecomercio-pe.com.br\/site\/?p=10610"},"modified":"2024-09-10T08:18:30","modified_gmt":"2024-09-10T11:18:30","slug":"inadimplencia-volta-a-subir-em-recife-apos-3-meses-de-queda","status":"publish","type":"post","link":"https:\/\/fecomercio-pe.com.br\/site\/inadimplencia-volta-a-subir-em-recife-apos-3-meses-de-queda\/","title":{"rendered":"Inadimpl\u00eancia volta a subir em Recife ap\u00f3s 3 meses de queda"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A Pesquisa de Endividamento e Inadimpl\u00eancia do Consumidor (PEIC) realizada pela Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo contou com um recorte pela Fecom\u00e9rcio-PE para Recife. A pesquisa indicou que, o total de fam\u00edlias endividadas atingiu 81,5%, um crescimento de 2,3 pontos percentuais em compara\u00e7\u00e3o com julho de 2024. A amostra revelou ainda que 28,6% das fam\u00edlias possuem contas em atraso e 16,1% afirmaram que n\u00e3o ter\u00e3o condi\u00e7\u00f5es de pagar suas d\u00edvidas no pr\u00f3ximo m\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O cart\u00e3o de cr\u00e9dito permanece como o principal tipo de d\u00edvida, sendo mencionado por 95,3% das fam\u00edlias endividadas. O financiamento de carros tamb\u00e9m se destaca entre as fam\u00edlias de maior renda (acima de 10 sal\u00e1rios m\u00ednimos), com 29% reportando esse tipo de d\u00edvida, enquanto para as fam\u00edlias com renda at\u00e9 10 sal\u00e1rios m\u00ednimos, o percentual \u00e9 de apenas 3,7%.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cO cart\u00e3o de cr\u00e9dito ainda se destaca como o principal meio de endividamento das fam\u00edlias pela facilidade do acesso ao cr\u00e9dito, especialmente dos bens de maior valor agregado. \u00c9 importante que empres\u00e1rios deste segmento estejam atentos a modalidade de pagamento que consigam atender ao p\u00fablico de menor renda.\u00a0 O aumento no endividamento e na inadimpl\u00eancia, mesmo que moderado, aponta a necessidade de medidas que incentivem a recupera\u00e7\u00e3o do emprego e a educa\u00e7\u00e3o financeira\u201d, destacou Bernardo Peixoto, presidente da Fecom\u00e9rcio-PE.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A inadimpl\u00eancia voltou a crescer em agosto, com 28,6% das fam\u00edlias endividadas relatando contas em atraso, frente aos 27,4% registrados em julho. Al\u00e9m disso, o percentual de fam\u00edlias que declararam n\u00e3o ter condi\u00e7\u00f5es de pagar suas d\u00edvidas subiu para 16,1%, um aumento de 0,4 ponto percentual em rela\u00e7\u00e3o ao m\u00eas anterior.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O cen\u00e1rio \u00e9 mais cr\u00edtico para as fam\u00edlias com renda de at\u00e9 10 sal\u00e1rios m\u00ednimos, das quais 37,7% possuem contas em atraso. Entre as fam\u00edlias de maior renda, esse percentual \u00e9 significativamente menor, atingindo apenas 7,4%.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Rafael Lima, economista da Fecom\u00e9rcio-PE, aponta que o aumento no endividamento e a eleva\u00e7\u00e3o moderada da inadimpl\u00eancia refletem um cen\u00e1rio de cr\u00e9dito restrito e recupera\u00e7\u00e3o lenta da renda familiar. &#8220;Com o mercado de trabalho ainda fragilizado e altos n\u00edveis de informalidade, a seletividade na concess\u00e3o de cr\u00e9dito tem limitado o poder de consumo das fam\u00edlias. Al\u00e9m disso, os custos adicionais decorrentes de juros e multas por inadimpl\u00eancia, especialmente no uso do cart\u00e3o de cr\u00e9dito, agravam a situa\u00e7\u00e3o financeira dos consumidores&#8221;, afirma.\u00a0<\/span><\/p>\n<p>Fecom\u00e9rcio-PE\u2013 A Federa\u00e7\u00e3o do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo do Estado de Pernambuco (Fecom\u00e9rcio-PE) realiza, mensalmente, pesquisas conjunturais, de sondagem de opini\u00e3o em datas comemorativas para o com\u00e9rcio e estudos especiais, atrav\u00e9s do Instituto Fecom\u00e9rcio-PE, e recortes locais das pesquisas da Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo (CNC) e dos \u00edndices do IBGE, atrav\u00e9s da sua Assessoria em Economia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pesquisa de Endividamento e Inadimpl\u00eancia do Consumidor (PEIC) realizada pela Confedera\u00e7\u00e3o Nacional do Com\u00e9rcio de Bens, Servi\u00e7os e Turismo contou com um recorte pela Fecom\u00e9rcio-PE para Recife. A pesquisa indicou que, o total de fam\u00edlias endividadas atingiu 81,5%, um crescimento de 2,3 pontos percentuais em compara\u00e7\u00e3o com julho de 2024. A amostra revelou ainda<br \/><a href=\"https:\/\/fecomercio-pe.com.br\/site\/inadimplencia-volta-a-subir-em-recife-apos-3-meses-de-queda\/\" class=\"more\">Read more<\/a><\/p>\n","protected":false},"author":12,"featured_media":10136,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4],"tags":[],"_links":{"self":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/10610"}],"collection":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/comments?post=10610"}],"version-history":[{"count":1,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/10610\/revisions"}],"predecessor-version":[{"id":10611,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/10610\/revisions\/10611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/media\/10136"}],"wp:attachment":[{"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/media?parent=10610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/categories?post=10610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/tags?post=10610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}