{"id":3013,"date":"2016-11-30T12:28:22","date_gmt":"2016-11-30T12:28:22","guid":{"rendered":"http:\/\/fecomercio-pe.com.br\/site\/?p=3013"},"modified":"2016-11-30T12:28:22","modified_gmt":"2016-11-30T12:28:22","slug":"indice-do-aluguel-cai-em-novembro-e-taxa-acumulada-e-de-712","status":"publish","type":"post","link":"http:\/\/fecomercio-pe.com.br\/site\/indice-do-aluguel-cai-em-novembro-e-taxa-acumulada-e-de-712\/","title":{"rendered":"\u00cdndice do aluguel cai em novembro e taxa acumulada \u00e9 de 7,12%"},"content":{"rendered":"<p><span style=\"color: #000000;\">O \u00cdndice Geral de Pre\u00e7os do Mercado (IGP-M) apresentou um recuo de 0,03%, em novembro ante uma alta de 0,16%, em outubro. A varia\u00e7\u00e3o tamb\u00e9m foi menor que a registrada em novembro do ano passado (1,52%). Com o resultado, no acumulado do ano, a taxa alcan\u00e7ou 6,60% e, em 12 meses, 7,12%, que \u00e9 o percentual utilizado na renova\u00e7\u00e3o em contratos de aluguel.<\/span><\/p>\n<p><span style=\"color: #000000;\">Calculado pelo Instituto Brasileiro de Economia da Funda\u00e7\u00e3o Getulio Vargas (Ibre\/FGV), o IGP-M indica a m\u00e9dia de pre\u00e7os de bens do atacado, varejo e da constru\u00e7\u00e3o civil no per\u00edodo entre os \u00faltimos dias 21 de outubro e 20 de novembro. Apesar de ter recuado, o \u00edndice de novembro reflete mais o comportamento de pre\u00e7os em um dos tr\u00eas componentes, o \u00cdndice de Pre\u00e7os ao Produtor Amplo, com queda de 0,16% ante uma alta de 0,15%.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Pre\u00e7os caem<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Neste componente, o destaque foi o grupo dos alimentos processados. Eles ficaram 0,08% mais baratos depois de um aumento de 1,58% na apura\u00e7\u00e3o anterior. As mat\u00e9rias-primas brutas, que incluem as varia\u00e7\u00f5es das commodities (produtos com cota\u00e7\u00e3o internacional), aceleraram com alta de 0,90% ante 0,36%. As eleva\u00e7\u00f5es mais significativas foram do min\u00e9rio de ferro (de 2,16% para 9,04%); do caf\u00e9 em gr\u00e3o (de 2,28% para 8,30%) e da cana-de-a\u00e7\u00facar (de 1,48% para 2,80%). Em sentido oposto, est\u00e3o o leite in natura (de -5,52% para -8,78%), o milho em gr\u00e3o (de -1,80% para -3,92%) e os bovinos (de 2,20% para 0,16%)<\/span><\/p>\n<p><span style=\"color: #000000;\">Em rela\u00e7\u00e3o ao \u00cdndice de Pre\u00e7os ao Consumidor (IPC) ocorreu varia\u00e7\u00e3o de 0,26%, taxa superior ao valor de outubro (0,17%) com acr\u00e9scimos registrados em cinco dos oito grupos pesquisados e destaque para educa\u00e7\u00e3o, leitura e recrea\u00e7\u00e3o (de -0,24% para 0,32%).<\/span><\/p>\n<p><span style=\"color: #000000;\">J\u00e1 o \u00cdndice Nacional de Custo da Constru\u00e7\u00e3o (INCC) manteve-se est\u00e1vel em 0,17%. No per\u00edodo, o \u00edndice sobre materiais, equipamentos e servi\u00e7os teve queda de 0,05%, enquanto a m\u00e3o de obra subiu de 0,30% para 0,36%.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Fonte:Ag\u00eancia Brasil<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Apesar de ter recuado, o \u00edndice de novembro reflete mais o comportamento de pre\u00e7os em um dos tr\u00eas componentes, o \u00cdndice de Pre\u00e7os ao Produtor Amplo, com queda de 0,16% ante uma alta de 0,15%.<\/p>\n","protected":false},"author":1,"featured_media":3015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/3013"}],"collection":[{"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/comments?post=3013"}],"version-history":[{"count":1,"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/3013\/revisions"}],"predecessor-version":[{"id":3016,"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/posts\/3013\/revisions\/3016"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/media\/3015"}],"wp:attachment":[{"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/media?parent=3013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/categories?post=3013"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/fecomercio-pe.com.br\/site\/wp-json\/wp\/v2\/tags?post=3013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}